{"id":67,"count":24,"description":"","link":"https:\/\/meilleursjeuxdesexe.net\/en\/jeux\/mobile\/","name":"Mobile","slug":"mobile","taxonomy":"jeux","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Meilleurs Jeux Porno Mobile de 2025<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/meilleursjeuxdesexe.net\/en\/games\/mobile\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Meilleurs Jeux Porno Mobile de 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/meilleursjeuxdesexe.net\/en\/games\/mobile\/\" \/>\n<meta property=\"og:site_name\" content=\"Meilleurs Jeux de Sexe - Le Top des Jeux Porno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/jeux\\\/mobile\\\/\",\"url\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/jeux\\\/mobile\\\/\",\"name\":\"Les Meilleurs Jeux Porno Mobile de 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/jeux\\\/mobile\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/jeux\\\/mobile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/#website\",\"url\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/\",\"name\":\"Meilleurs Jeux de Sexe - Le Top des Jeux Porno\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/#organization\",\"name\":\"Meilleurs Jeux de Sexe - Le Top des Jeux Porno\",\"url\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo.png\",\"width\":534,\"height\":43,\"caption\":\"Meilleurs Jeux de Sexe - Le Top des Jeux Porno\"},\"image\":{\"@id\":\"https:\\\/\\\/meilleursjeuxdesexe.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Meilleurs Jeux Porno Mobile de 2025","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/meilleursjeuxdesexe.net\/en\/games\/mobile\/","og_locale":"en_GB","og_type":"article","og_title":"Les Meilleurs Jeux Porno Mobile de 2025","og_url":"https:\/\/meilleursjeuxdesexe.net\/en\/games\/mobile\/","og_site_name":"Meilleurs Jeux de Sexe - Le Top des Jeux Porno","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/meilleursjeuxdesexe.net\/jeux\/mobile\/","url":"https:\/\/meilleursjeuxdesexe.net\/jeux\/mobile\/","name":"The Best Mobile Porn Games of 2025","isPartOf":{"@id":"https:\/\/meilleursjeuxdesexe.net\/#website"},"breadcrumb":{"@id":"https:\/\/meilleursjeuxdesexe.net\/jeux\/mobile\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/meilleursjeuxdesexe.net\/jeux\/mobile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/meilleursjeuxdesexe.net\/"},{"@type":"ListItem","position":2,"name":"Mobile"}]},{"@type":"WebSite","@id":"https:\/\/meilleursjeuxdesexe.net\/#website","url":"https:\/\/meilleursjeuxdesexe.net\/","name":"Best Sex Games - Top Porn Games","description":"","publisher":{"@id":"https:\/\/meilleursjeuxdesexe.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/meilleursjeuxdesexe.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/meilleursjeuxdesexe.net\/#organization","name":"Best Sex Games - Top Porn Games","url":"https:\/\/meilleursjeuxdesexe.net\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/meilleursjeuxdesexe.net\/#\/schema\/logo\/image\/","url":"https:\/\/meilleursjeuxdesexe.net\/wp-content\/uploads\/2020\/05\/logo.png","contentUrl":"https:\/\/meilleursjeuxdesexe.net\/wp-content\/uploads\/2020\/05\/logo.png","width":534,"height":43,"caption":"Meilleurs Jeux de Sexe - Le Top des Jeux Porno"},"image":{"@id":"https:\/\/meilleursjeuxdesexe.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/meilleursjeuxdesexe.net\/en\/wp-json\/wp\/v2\/jeux\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meilleursjeuxdesexe.net\/en\/wp-json\/wp\/v2\/jeux"}],"about":[{"href":"https:\/\/meilleursjeuxdesexe.net\/en\/wp-json\/wp\/v2\/taxonomies\/jeux"}],"wp:post_type":[{"href":"https:\/\/meilleursjeuxdesexe.net\/en\/wp-json\/wp\/v2\/jeux-porno?jeux=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}